{"id":55,"count":1,"description":"","link":"https:\/\/digitalgamedeals.com\/videogame\/tag\/logitech-g400\/","name":"Logitech G400","slug":"logitech-g400","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/digitalgamedeals.com\/videogame\/wp-json\/wp\/v2\/tags\/55","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digitalgamedeals.com\/videogame\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/digitalgamedeals.com\/videogame\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/digitalgamedeals.com\/videogame\/wp-json\/wp\/v2\/posts?tags=55"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}