{"id":51,"count":1,"description":"","link":"https:\/\/digitalgamedeals.com\/videogame\/tag\/turtle-beach\/","name":"Turtle Beach","slug":"turtle-beach","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/digitalgamedeals.com\/videogame\/wp-json\/wp\/v2\/tags\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digitalgamedeals.com\/videogame\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/digitalgamedeals.com\/videogame\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/digitalgamedeals.com\/videogame\/wp-json\/wp\/v2\/posts?tags=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}